{"id":24923,"date":"2022-04-14T11:53:34","date_gmt":"2022-04-14T11:04:07","guid":{"rendered":"https:\/\/ledial.it\/product\/lapis-lazuli-necklace\/"},"modified":"2025-06-19T13:23:50","modified_gmt":"2025-06-19T11:23:50","slug":"lapis-lazuli-necklace","status":"publish","type":"product","link":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/","title":{"rendered":"Lapis lazuli necklace"},"content":{"rendered":"<p>Necklace with 10-10.5mm lapis lazuli spheres, with 18kt yellow gold push clasp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Necklace with 10-10.5mm lapis lazuli spheres, with 18kt yellow gold push clasp.<\/p>\n","protected":false},"featured_media":24484,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2581],"product_tag":[6015,6217,2708,2673],"class_list":["post-24923","product","type-product","status-publish","has-post-thumbnail","product_cat-necklaces","product_tag-lapis-lazuli","product_tag-made-in-itlay-en","product_tag-collana-en","product_tag-yellow-gold","first","outofstock","sale","sold-individually","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lapis lazuli necklace - Ledial<\/title>\n<meta name=\"description\" content=\"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lapis lazuli necklace - Ledial\" \/>\n<meta property=\"og:description\" content=\"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T11:23:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ledial.test.emberware.it\/app\/uploads\/2022\/04\/27938-collana-oro-lapislazzuli-sito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/\",\"name\":\"Lapis lazuli necklace - Ledial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ledial.test.emberware.it\\\/app\\\/uploads\\\/2022\\\/04\\\/27938-collana-oro-lapislazzuli-sito.jpg\",\"datePublished\":\"2022-04-14T11:04:07+00:00\",\"dateModified\":\"2025-06-19T11:23:50+00:00\",\"description\":\"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/app\\\/uploads\\\/2022\\\/04\\\/27938-collana-oro-lapislazzuli-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/ledial.test.emberware.it\\\/app\\\/uploads\\\/2022\\\/04\\\/27938-collana-oro-lapislazzuli-sito.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"collana di lapislazzuli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/prodotto\\\/lapis-lazuli-necklace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lapis lazuli necklace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"name\":\"Ledial\",\"description\":\"Nel mondo dell\u2019oro da 20 anni\",\"publisher\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\",\"name\":\"Ledial S.R.L\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"contentUrl\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"width\":1666,\"height\":1497,\"caption\":\"Ledial S.R.L\"},\"image\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lapis lazuli necklace - Ledial","description":"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Lapis lazuli necklace - Ledial","og_description":"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online","og_url":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/","og_site_name":"Ledial","article_modified_time":"2025-06-19T11:23:50+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/ledial.test.emberware.it\/app\/uploads\/2022\/04\/27938-collana-oro-lapislazzuli-sito.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/","url":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/","name":"Lapis lazuli necklace - Ledial","isPartOf":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/#primaryimage"},"image":{"@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/#primaryimage"},"thumbnailUrl":"https:\/\/ledial.test.emberware.it\/app\/uploads\/2022\/04\/27938-collana-oro-lapislazzuli-sito.jpg","datePublished":"2022-04-14T11:04:07+00:00","dateModified":"2025-06-19T11:23:50+00:00","description":"Buy now Lapis lazuli necklace on Ledial. Buy Gold and sell used jewelry online","breadcrumb":{"@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/#primaryimage","url":"https:\/\/ledial.test.emberware.it\/app\/uploads\/2022\/04\/27938-collana-oro-lapislazzuli-sito.jpg","contentUrl":"https:\/\/ledial.test.emberware.it\/app\/uploads\/2022\/04\/27938-collana-oro-lapislazzuli-sito.jpg","width":1000,"height":1000,"caption":"collana di lapislazzuli"},{"@type":"BreadcrumbList","@id":"https:\/\/ledial.test.emberware.it\/en\/prodotto\/lapis-lazuli-necklace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ledial.test.emberware.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/ledial.test.emberware.it\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Lapis lazuli necklace"}]},{"@type":"WebSite","@id":"https:\/\/ledial.test.emberware.it\/en\/#website","url":"https:\/\/ledial.test.emberware.it\/en\/","name":"Ledial","description":"Nel mondo dell\u2019oro da 20 anni","publisher":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ledial.test.emberware.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ledial.test.emberware.it\/en\/#organization","name":"Ledial S.R.L","url":"https:\/\/ledial.test.emberware.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","contentUrl":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","width":1666,"height":1497,"caption":"Ledial S.R.L"},"image":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product\/24923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product\/24923\/revisions"}],"predecessor-version":[{"id":72413,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product\/24923\/revisions\/72413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/media\/24484"}],"wp:attachment":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/media?parent=24923"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_brand?post=24923"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_cat?post=24923"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_tag?post=24923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}