{"id":2571,"count":50,"description":"","link":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/","name":"Riviere","slug":"riviere-en","taxonomy":"product_cat","parent":2566,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial<\/title>\n<meta name=\"description\" content=\"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/products\\\/rings\\\/riviere-en\\\/\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/products\\\/rings\\\/riviere-en\\\/\",\"name\":\"Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\"},\"description\":\"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/products\\\/rings\\\/riviere-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/products\\\/rings\\\/riviere-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rings\",\"item\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/products\\\/rings\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Riviere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"name\":\"Ledial\",\"description\":\"Nel mondo dell\u2019oro da 20 anni\",\"publisher\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\",\"name\":\"Ledial S.R.L\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"contentUrl\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"width\":1666,\"height\":1497,\"caption\":\"Ledial S.R.L\"},\"image\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial","description":"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial","og_description":"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.","og_url":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/","og_site_name":"Ledial","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/","url":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/","name":"Anelli Veretta con Diamanti in Oro Bianco e Oro Giallo - Ledial","isPartOf":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#website"},"description":"Scopri tutti gli anelli riviere o veretta con diamanti in oro bianco e oro giallo su Ledial. Compro Oro e vendita gioielli usati online.","breadcrumb":{"@id":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ledial.test.emberware.it\/en\/"},{"@type":"ListItem","position":2,"name":"Rings","item":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/"},{"@type":"ListItem","position":3,"name":"Riviere"}]},{"@type":"WebSite","@id":"https:\/\/ledial.test.emberware.it\/en\/#website","url":"https:\/\/ledial.test.emberware.it\/en\/","name":"Ledial","description":"Nel mondo dell\u2019oro da 20 anni","publisher":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ledial.test.emberware.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ledial.test.emberware.it\/en\/#organization","name":"Ledial S.R.L","url":"https:\/\/ledial.test.emberware.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","contentUrl":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","width":1666,"height":1497,"caption":"Ledial S.R.L"},"image":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/"}}]}},"cat_url":"https:\/\/ledial.test.emberware.it\/en\/products\/rings\/riviere-en\/","_links":{"self":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_cat\/2571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product_cat\/2566"}],"wp:post_type":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/product?product_cat=2571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}