{"id":8182,"count":1,"description":"","link":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/","name":"gold quotes","slug":"gold-quotes","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>gold quotes - Ledial<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gold quotes - Ledial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/tag\\\/gold-quotes\\\/\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/tag\\\/gold-quotes\\\/\",\"name\":\"gold quotes - Ledial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/tag\\\/gold-quotes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/tag\\\/gold-quotes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gold quotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"name\":\"Ledial\",\"description\":\"Nel mondo dell\u2019oro da 20 anni\",\"publisher\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#organization\",\"name\":\"Ledial S.R.L\",\"url\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"contentUrl\":\"https:\\\/\\\/ledial.it\\\/app\\\/uploads\\\/2020\\\/09\\\/label_ledial_big.png\",\"width\":1666,\"height\":1497,\"caption\":\"Ledial S.R.L\"},\"image\":{\"@id\":\"https:\\\/\\\/ledial.test.emberware.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gold quotes - Ledial","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"gold quotes - Ledial","og_url":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/","og_site_name":"Ledial","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/","url":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/","name":"gold quotes - Ledial","isPartOf":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ledial.test.emberware.it\/en\/tag\/gold-quotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ledial.test.emberware.it\/en\/"},{"@type":"ListItem","position":2,"name":"gold quotes"}]},{"@type":"WebSite","@id":"https:\/\/ledial.test.emberware.it\/en\/#website","url":"https:\/\/ledial.test.emberware.it\/en\/","name":"Ledial","description":"Nel mondo dell\u2019oro da 20 anni","publisher":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ledial.test.emberware.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ledial.test.emberware.it\/en\/#organization","name":"Ledial S.R.L","url":"https:\/\/ledial.test.emberware.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","contentUrl":"https:\/\/ledial.it\/app\/uploads\/2020\/09\/label_ledial_big.png","width":1666,"height":1497,"caption":"Ledial S.R.L"},"image":{"@id":"https:\/\/ledial.test.emberware.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/tags\/8182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ledial.test.emberware.it\/en\/wp-json\/wp\/v2\/posts?tags=8182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}